{"id":6045,"date":"2025-08-20T08:24:37","date_gmt":"2025-08-20T08:24:37","guid":{"rendered":"https:\/\/eatcard.nl\/solution\/grab-go\/"},"modified":"2026-07-10T07:38:26","modified_gmt":"2026-07-10T07:38:26","slug":"zelfscankassa","status":"publish","type":"solution","link":"https:\/\/eatcard.nl\/nl\/solution\/zelfscankassa\/","title":{"rendered":"Grab &amp; Go"},"content":{"rendered":"    <div class=\"featured-module featured-module--overlap-80\" style=\"background-color: #322721; color: #FFFFFF\" >\n        <div class=\"inner\">\n            <div class=\"text-comp-wrap\">\n                <h5><strong>Zelfscankassa voor horeca<\/strong><\/h5>\n                <h1>E\u00e9n scan, en je klant is direct geholpen.<\/h1>\n                                    <div class=\"btns-wrap\">\n                            <div class=\"btn light-gray-btn\">\n        <a  href=\"https:\/\/eatcard.nl\/book-a-demo\/\">Book a demo<\/a>\n    <\/div>\n                    <\/div><!--end of btns-wrap-->\n                            <\/div><!--end of text-comp-wrap-->\n\n            <div class=\"featured-module__media-wrap\">\n                                <div class=\"featured-module__media-wrap-inner cover\">\n                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Grabgo-2-2-copy-scaled.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Grabgo-2-2-copy-scaled.webp'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Grabgo-2-2-copy-scaled.webp\">    <\/picture>\n\n                <\/div><!--end of featured-module__media-wrap-inner-->\n            <\/div><!--end of featured-module__media-wrap-->\n        <\/div><!--end of inner-->\n    <\/div><!--end of featured-module-->\n\n\n    <div class=\"logo-module\" >\n        <div class=\"inner cf\">\n            <div class=\"trusted-wrap\">\n                <span class=\"trusted-wrap__label\">Vertrouwd door <span class=\"trusted-wrap__label-highlight\">200+ ondernemers<\/span><\/span>\n                                    <div class=\"trusted-wrap__users\">\n                                                    <div class=\"trusted-wrap__user\">\n                                \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Cafe-Gogi.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Cafe-Gogi.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Cafe-Gogi.png\">    <\/picture>\n\n                            <\/div><!--end of trusted-wrap__user-->\n                                                        <div class=\"trusted-wrap__user\">\n                                \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Seoul-Sista.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Seoul-Sista.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Seoul-Sista.jpg\">    <\/picture>\n\n                            <\/div><!--end of trusted-wrap__user-->\n                                                        <div class=\"trusted-wrap__user\">\n                                \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Bakkerij-Renzema.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Bakkerij-Renzema.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Bakkerij-Renzema.jpg\">    <\/picture>\n\n                            <\/div><!--end of trusted-wrap__user-->\n                                                        <div class=\"trusted-wrap__user\">\n                                \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Blue-Dragon.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Blue-Dragon.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Blue-Dragon.jpg\">    <\/picture>\n\n                            <\/div><!--end of trusted-wrap__user-->\n                                                <\/div><!--end of trusted-wrap__users-->\n                                <\/div><!--end of trusted-wrap-->\n                            <div class=\"logo-module__slider swiper\">\n                    <div class=\"swiper-wrapper\">\n                                                    <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Amazing-Taste_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Amazing-Taste_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Amazing-Taste_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Donerland_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Donerland_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Donerland_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Gaja_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Gaja_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Gaja_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Ichi_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Ichi_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Ichi_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Intermezzo_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Intermezzo_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Intermezzo_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Luchroom_Rooyaal_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Luchroom_Rooyaal_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Luchroom_Rooyaal_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/machi-machi_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/machi-machi_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/machi-machi_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Mojo_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Mojo_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Mojo_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Popsyz_logo-1.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Popsyz_logo-1.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Popsyz_logo-1.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Seou-Sista_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Seou-Sista_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Seou-Sista_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Warung-Mini_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Warung-Mini_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Warung-Mini_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Wok-to-go_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Wok-to-go_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/Wok-to-go_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/YoYo_logo.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/YoYo_logo.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/YoYo_logo.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Pad-Thai.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Pad-Thai.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Pad-Thai.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Maruki.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Maruki.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Maruki.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Mama-Hong.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Mama-Hong.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Mama-Hong.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Off-smash.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Off-smash.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/08\/Off-smash.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                        <div class=\"swiper-slide\">\n                                <div class=\"logo-module__img-wrap\">\n                                    \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/06\/TrippleClub.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/06\/TrippleClub.png'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/06\/TrippleClub.png\">    <\/picture>\n\n                                <\/div><!--end of logo-module__img-wrap-->\n                            <\/div><!--end of swiper-slide-->\n                                                <\/div><!--end of swiper-wrapper-->\n                <\/div><!--end of logo-module__slider-->\n                        <\/div><!--end of inner-->\n    <\/div><!--end of logo-module-->\n    \n\n    <div class=\"information-blocks-module\" >\n        <div class=\"inner cf\">\n            <div class=\"text-comp-wrap\">\n                <h2>Wat als je producten zichzelf konden verkopen?<\/h2>\n<p class=\"large-text\">Met een zelfscankassa scant je gast eenvoudig een QR-code op het product, voegt deze direct toe aan het mandje en rekent meteen af bij de kiosk of kassa. Geen rij, geen personeel nodig bij het afrekenmoment, gewoon scannen en gaan.<\/p>\n            <\/div><!--end of text-comp-wrap-->\n                            <div class=\"grid-module\">\n                                            <div class=\"grid-module__item grid-module__item--two-third\" style=\"background-color: ;\">\n                            <div class=\"unit-wrap unit-wrap--featured default unit-wrap--align-left unit-wrap--content-top   \">\n                                <div class=\"unit-wrap__text\">\n                                    <div class=\"text-comp-wrap\">\n                                        <h3>Direct bestellen<\/h3>\n<p>Elk kant-en-klaar product krijgt een unieke QR-code. Je gast scant deze bij de kiosk of kassa en rekent direct af, zonder tussenkomst van personeel.<\/p>\n                                    <\/div><!--end of text-comp-wrap-->\n                                <\/div><!--end of unit-wrap__text-->\n                                                                    <div class=\"unit-wrap__image\">\n                                                                                            <picture>\n                                                                    <source media=\"(width &lt; 500px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_400_instant_ordering.webp'>            <source media=\"(width &lt; 500px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_400_instant_ordering.webp'>                <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_741_instant_ordering-1.webp'>            <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_741_instant_ordering-1.webp'>                <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_933_instant_ordering-1.webp'>            <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_933_instant_ordering-1.webp'>                <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo__1200_instant_ordering-1.webp'>            <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo__1200_instant_ordering-1.webp'>            <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo__1200_instant_ordering-1.png\">\n                                                        <\/picture>\n                                                                            <\/div><!--end of unit-wrap__image-->\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"grid-module__item default\" style=\"background-color: ;\">\n                            <div class=\"unit-wrap unit-wrap--featured default center unit-wrap--content-top   \">\n                                <div class=\"unit-wrap__text\">\n                                    <div class=\"text-comp-wrap\">\n                                        <h3>Naadloos afrekenen<\/h3>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Geen wachtrijen, geen handmatige invoer. De hele ervaring voor je gasten verloopt sneller en soepeler dankzij zelfscannen.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">\n                                    <\/div><!--end of text-comp-wrap-->\n                                <\/div><!--end of unit-wrap__text-->\n                                                                    <div class=\"unit-wrap__image\">\n                                                                                            <picture>\n                                                                    <source media=\"(width &lt; 400px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_400_seamless-checkout.webp'>            <source media=\"(width &lt; 400px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_400_seamless-checkout.webp'>                <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_741_seamless-checkout.webp'>            <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_741_seamless-checkout.webp'>                <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_993_seamless-checkout.webp'>            <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo_993_seamless-checkout.webp'>                <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo__1200_seamless-checkout.webp'>            <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo__1200_seamless-checkout.webp'>            <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/08\/GrabGo__1200_seamless-checkout.png\">\n                                                        <\/picture>\n                                                                            <\/div><!--end of unit-wrap__image-->\n                                                            <\/div>\n                        <\/div>\n                                    <\/div>\n                    <\/div><!--end of inner-->\n    <\/div><!--end of information-blocks-module-->\n\n\n    <div class=\"features-module\" >\n        <div class=\"inner cf\">\n            <div class=\"text-comp-wrap\">\n                <h2>Alles wat je nodig hebt voor een snelle zelfscankassa ervaring<\/h2>\n                <p class=\"large-text\">Ontdek de belangrijkste functies van de zelfscankassa, Grab &amp; Go die kant-en-klare producten razendsnel afrekent en je gasten zonder wachtrij verder helpt.<\/p>\n                <p class=\"large-text\"><\/p>\n            <\/div><!--end of text-comp-wrap-->\n                                <div class=\"grid-module\">\n                                                    <div class=\"grid-module__item grid-module__item--one-fourth\">\n                                <div class=\"feature-item\">\n                                    <div class=\"feature-item__icon\">\n                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/QR@2x.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/QR@2x.webp'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/QR@2x.webp\">    <\/picture>\n\n                                    <\/div><!--end of feature-item__icon-->\n\n                                    <div class=\"feature-item__text-wrap\">\n                                        <h4>Unieke QR per product<\/h4>\n                                        Elk kant-en-klaar product met zijn eigen scanbare code                                    <\/div><!--end of feature-item__text-wrap-->\n                                <\/div><!--end of feature-item-->\n                            <\/div><!--end of grid-module__item-->\n                                                        <div class=\"grid-module__item grid-module__item--one-fourth\">\n                                <div class=\"feature-item\">\n                                    <div class=\"feature-item__icon\">\n                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Payment@2x.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Payment@2x.webp'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Payment@2x.webp\">    <\/picture>\n\n                                    <\/div><!--end of feature-item__icon-->\n\n                                    <div class=\"feature-item__text-wrap\">\n                                        <h4>Snel afrekenen<\/h4>\n                                        Zelfscannen en direct betalen, zonder wachtrij                                    <\/div><!--end of feature-item__text-wrap-->\n                                <\/div><!--end of feature-item-->\n                            <\/div><!--end of grid-module__item-->\n                                                        <div class=\"grid-module__item grid-module__item--one-fourth\">\n                                <div class=\"feature-item\">\n                                    <div class=\"feature-item__icon\">\n                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Tips@2x.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Tips@2x.webp'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Tips@2x.webp\">    <\/picture>\n\n                                    <\/div><!--end of feature-item__icon-->\n\n                                    <div class=\"feature-item__text-wrap\">\n                                        <h4>Onbemand verkopen<\/h4>\n                                        Kant-en-klare producten verkopen zonder personeel aan de kassa                                    <\/div><!--end of feature-item__text-wrap-->\n                                <\/div><!--end of feature-item-->\n                            <\/div><!--end of grid-module__item-->\n                                                        <div class=\"grid-module__item grid-module__item--one-fourth\">\n                                <div class=\"feature-item\">\n                                    <div class=\"feature-item__icon\">\n                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Paymend-copy@2x.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Paymend-copy@2x.webp'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Paymend-copy@2x.webp\">    <\/picture>\n\n                                    <\/div><!--end of feature-item__icon-->\n\n                                    <div class=\"feature-item__text-wrap\">\n                                        <h4>Meerdere betaalopties<\/h4>\n                                        Accepteer kaarten, contant, iDEAL en cadeaubonnen voor een soepel afrekenproces.                                    <\/div><!--end of feature-item__text-wrap-->\n                                <\/div><!--end of feature-item-->\n                            <\/div><!--end of grid-module__item-->\n                                                <\/div>\n                                <div class=\"features-module__toggle\">\n                <div class=\"btn\">\n                    <span>Show More<\/span>\n                <\/div>\n            <\/div>\n        <\/div><!--end of inner-->\n    <\/div><!--end of features-module-->\n\n\n\n    <div class=\"faq-module\" >\n        <div class=\"inner cf\">\n            <div class=\"text-comp-wrap\">\n                <h2>Veelgestelde vragen<\/h2>            <\/div><!--end of text-comp-wrap-->\n                                <div class=\"accordion-wrap\">\n                                                    <div class=\"accordion-section\">\n                                <a class=\"accordion-section-title\" href=\"#accordion-1\">\n                                    <span>Wat is self-checkout?<\/span>\n                                    <span class=\"icon\"><\/span>\n                                <\/a>\n                                <div id=\"accordion-1\" class=\"accordion-section-content\">\n                                    <div class=\"accordion-content-inner\">\n                                        <div class=\"text-comp-block\"><p class=\"font-claude-response-body break-words whitespace-normal\">Met self-checkout kunnen gasten zelf een QR-code op een product scannen, het product aan hun winkelmand toevoegen en direct afrekenen via de bestelzuil of het kassasysteem, zonder hulp van het personeel.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">\n<\/div><!--end of text-comp-block-->\n                                    <\/div><!--end of accordion-content-inner-->\n                                <\/div><!--end of accordion-section-content-->\n                            <\/div><!--end of accordion-section-->\n                                                        <div class=\"accordion-section\">\n                                <a class=\"accordion-section-title\" href=\"#accordion-2\">\n                                    <span>Kan ik self-checkout gebruiken zonder een bestelzuil?<\/span>\n                                    <span class=\"icon\"><\/span>\n                                <\/a>\n                                <div id=\"accordion-2\" class=\"accordion-section-content\">\n                                    <div class=\"accordion-content-inner\">\n                                        <div class=\"text-comp-block\"><p class=\"font-claude-response-body break-words whitespace-normal\">Ja. Self-checkout werkt als een losse oplossing, of je kunt het combineren met een bestelzuil om op hetzelfde apparaat ook volledige menubestellingen aan te bieden.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">\n<\/div><!--end of text-comp-block-->\n                                    <\/div><!--end of accordion-content-inner-->\n                                <\/div><!--end of accordion-section-content-->\n                            <\/div><!--end of accordion-section-->\n                                                        <div class=\"accordion-section\">\n                                <a class=\"accordion-section-title\" href=\"#accordion-3\">\n                                    <span>Is self-checkout ge\u00efntegreerd met andere Eatcard-modules?<\/span>\n                                    <span class=\"icon\"><\/span>\n                                <\/a>\n                                <div id=\"accordion-3\" class=\"accordion-section-content\">\n                                    <div class=\"accordion-content-inner\">\n                                        <div class=\"text-comp-block\"><p class=\"font-claude-response-body break-words whitespace-normal\">Ja. Self-checkout werkt direct samen met je bestelzuil, kassasysteem en rapportages, zodat elke verkoop wordt verwerkt binnen je bestaande systeem.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">\n<\/div><!--end of text-comp-block-->\n                                    <\/div><!--end of accordion-content-inner-->\n                                <\/div><!--end of accordion-section-content-->\n                            <\/div><!--end of accordion-section-->\n                                                <\/div><!--end of accordion-wrap-->\n                            <\/div><!--end of inner-->\n    <\/div><!--end of faq-module-->\n    \n\n    <div class=\"content-slider-module content-slider-module--products default\" >\n        <div class=\"inner\">\n            <div class=\"text-comp-wrap\">\n                <h2>Ontdek meer oplossingen.<\/h2>\n                <p class=\"large-text\">Lees meer over onze andere oplossingen die vaak worden gekozen en gecombineerd.<\/p>            <\/div><!--end of text-comp-wrap-->\n                            <div class=\"content-slider-module__container\">\n                    <div class=\"swiper\">\n                        <div class=\"swiper-wrapper\">\n                                                            <div class=\"swiper-slide\">\n                                    <div class=\"unit-wrap default center \">\n                                                                                    <div class=\"unit-wrap__text\">\n                                                <div class=\"text-comp-wrap\">\n                                                    <h3>QR bestellen<\/h3>\n<p class=\"large-text\">Laat gasten rechtstreeks vanaf hun tafel bestellen en betalen, zonder extra personeel.<\/p>\n                                                                                                            <div class=\"btns-wrap\">\n                                                            <div class=\"btn\">\n                                                                <a href=\"https:\/\/eatcard.nl\/nl\/solution\/qr-bestellen\/\">Meer informatie<\/a>\n                                                            <\/div>\n                                                        <\/div>\n                                                                                                    <\/div><!--end of text-comp-wrap-->\n                                            <\/div><!--end of unit-wrap__text-->\n\n                                            <div class=\"unit-wrap__image\">\n                                                                                                        <picture>\n                                                                        <source media=\"(width &lt; 400px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__400_QR-1-1.webp'>            <source media=\"(width &lt; 400px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__400_QR-1-1.webp'>                <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__741_QR-1-1.webp'>            <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__741_QR-1-1.webp'>                <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__993_QR-1-1.webp'>            <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__993_QR-1-1.webp'>                <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_QR-4-1.webp'>            <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_QR-4-1.webp'>            <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_QR-4-1.webp\">\n                                                            <\/picture>\n                                                                                            <\/div>\n                                                                            <\/div><!--end of text-media-wrap-->\n                                <\/div><!--end of swiper-slide-->\n                                                            <div class=\"swiper-slide\">\n                                    <div class=\"unit-wrap default center \">\n                                                                                    <div class=\"unit-wrap__text\">\n                                                <div class=\"text-comp-wrap\">\n                                                    <h3>Kitchen Display System<\/h3>\n<p class=\"large-text\">Stroomlijn het keukenproces met de KDS<\/p>\n                                                                                                            <div class=\"btns-wrap\">\n                                                            <div class=\"btn\">\n                                                                <a href=\"https:\/\/eatcard.nl\/nl\/solution\/keukenscherm\/\">Meer informatie<\/a>\n                                                            <\/div>\n                                                        <\/div>\n                                                                                                    <\/div><!--end of text-comp-wrap-->\n                                            <\/div><!--end of unit-wrap__text-->\n\n                                            <div class=\"unit-wrap__image\">\n                                                                                                        <picture>\n                                                                        <source media=\"(width &lt; 400px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__400_KDS-2-1.webp'>            <source media=\"(width &lt; 400px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__400_KDS-2-1.webp'>                <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__741_KDS-2-1.webp'>            <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__741_KDS-2-1.webp'>                <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__993_KDS-2-1.webp'>            <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__993_KDS-2-1.webp'>                <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_KDS-2-1.webp'>            <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_KDS-2-1.webp'>            <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_KDS-2-1.webp\">\n                                                            <\/picture>\n                                                                                            <\/div>\n                                                                            <\/div><!--end of text-media-wrap-->\n                                <\/div><!--end of swiper-slide-->\n                                                            <div class=\"swiper-slide\">\n                                    <div class=\"unit-wrap default center \">\n                                                                                    <div class=\"unit-wrap__text\">\n                                                <div class=\"text-comp-wrap\">\n                                                    <h3 aria-hidden=\"true\">Kassasysteem<\/h3>\n<p class=\"large-text\">Beheer alles vanuit \u00e9\u00e9n krachtig centrum.<\/p>\n                                                                                                            <div class=\"btns-wrap\">\n                                                            <div class=\"btn\">\n                                                                <a href=\"https:\/\/eatcard.nl\/nl\/solution\/kassasysteem\/\">Meer informatie<\/a>\n                                                            <\/div>\n                                                        <\/div>\n                                                                                                    <\/div><!--end of text-comp-wrap-->\n                                            <\/div><!--end of unit-wrap__text-->\n\n                                            <div class=\"unit-wrap__image\">\n                                                                                                        <picture>\n                                                                        <source media=\"(width &lt; 400px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__400_POS-2.webp'>            <source media=\"(width &lt; 400px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__400_POS-2.webp'>                <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__741_POS-1.webp'>            <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__741_POS-1.webp'>                <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__993_POS-1.webp'>            <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__993_POS-1.webp'>                <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_POS-1.webp'>            <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_POS-1.webp'>            <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_POS-1.png\">\n                                                            <\/picture>\n                                                                                            <\/div>\n                                                                            <\/div><!--end of text-media-wrap-->\n                                <\/div><!--end of swiper-slide-->\n                                                            <div class=\"swiper-slide\">\n                                    <div class=\"unit-wrap default center \">\n                                                                                    <div class=\"unit-wrap__text\">\n                                                <div class=\"text-comp-wrap\">\n                                                    <h3>Reserveringssyteem<\/h3>\n<p class=\"large-text\">Geen dubbel werk meer voor je reserveringen. Laat ons het regelen<\/p>\n                                                                                                            <div class=\"btns-wrap\">\n                                                            <div class=\"btn\">\n                                                                <a href=\"https:\/\/eatcard.nl\/nl\/solution\/reserveringssysteem\/\">Meer informatie<\/a>\n                                                            <\/div>\n                                                        <\/div>\n                                                                                                    <\/div><!--end of text-comp-wrap-->\n                                            <\/div><!--end of unit-wrap__text-->\n\n                                            <div class=\"unit-wrap__image\">\n                                                                                                        <picture>\n                                                                        <source media=\"(width &lt; 400px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__400_Reservation-4.webp'>            <source media=\"(width &lt; 400px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__400_Reservation-4.webp'>                <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__741_Reservation-4.webp'>            <source media=\"(width &lt; 740px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__741_Reservation-4.webp'>                <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__993_Reservation-3.webp'>            <source media=\"(width &lt; 992px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__993_Reservation-3.webp'>                <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_Reservation-3.webp'>            <source media=\"(width &gt;= 1200px)\" type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_Reservation-3.webp'>            <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Discover_more_solutions__1200_Reservation-3.png\">\n                                                            <\/picture>\n                                                                                            <\/div>\n                                                                            <\/div><!--end of text-media-wrap-->\n                                <\/div><!--end of swiper-slide-->\n                                                    <\/div><!--end of swiper-wrapper-->\n\n                        <!-- Add Pagination -->\n                        <div class=\"swiper-pagination\"><\/div>\n                    <\/div><!--end of swiper-->\n                <\/div><!--end of content-slider-module__container-->\n                    <\/div><!--end of inner-->\n    <\/div><!--end of content-slider-module-->\n\n\n    <div class=\"services-block-module\" >\n        <div class=\"inner cf\">\n                            <div class=\"text-comp-wrap\">\n                    <h2>Expert in jouw branche.<\/h2>\n<p class=\"large-text\">Van caf\u00e9s tot fine dining: ontdek hoe Eatcard bij jouw bedrijf past en helpt om alles soepeler, sneller en slimmer te laten verlopen.<\/p>\n                <\/div><!--end of text-comp-wrap-->\n                \n            <div class=\"grid-module\">\n                                                <div class=\"grid-module__item\">\n                                    <div class=\"text-comp-wrap\">\n                                        <h4>All you can eat<\/h4>\n                                        <p>Van sushi en Koreaanse BBQ tot elk AYCE-concept: Eatcard biedt de alles-in-\u00e9\u00e9n oplossing om je bedrijfsvoering te stroomlijnen.<\/p>\n\n                                        <div class=\"btns-wrap\">\n                                                <div class=\"btn light-gray-btn\">\n        <a  href=\"https:\/\/eatcard.nl\/nl\/business-type\/all-you-can-eat\/\">Ontdek All you can eat<\/a>\n    <\/div>\n                                        <\/div><!--end of btns-wrap-->\n                                    <\/div><!--end of text-comp-wrap-->\n                                                                            <div class=\"logo-blocks-wrap\">\n                                                                                                <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-7.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-7.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-7.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-8.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-8.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-8.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-9.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-9.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-9.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-12.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-12.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-12.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-13.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-13.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-13.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-15.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-15.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-15.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                            <\/div>\n                                                                        <\/div><!--end of grid-module__item-->\n                                                                <div class=\"grid-module__item\">\n                                    <div class=\"text-comp-wrap\">\n                                        <h4>Fast Dining<\/h4>\n                                        <p>Snelheid en effici\u00ebntie zijn alles in fast dining. Eatcard vereenvoudigt je bestelproces, communicatie met personeel en betalingen.<\/p>\n\n                                        <div class=\"btns-wrap\">\n                                                <div class=\"btn light-gray-btn\">\n        <a  href=\"https:\/\/eatcard.nl\/nl\/solution\/zelfscankassa\/\">Ontdek Fast Dining<\/a>\n    <\/div>\n                                        <\/div><!--end of btns-wrap-->\n                                    <\/div><!--end of text-comp-wrap-->\n                                                                            <div class=\"logo-blocks-wrap\">\n                                                                                                <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-3.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-3.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-3.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-2.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-2.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-2.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-4.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-4.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-4.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-6.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-6.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-6.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-14.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-14.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-14.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Mama-hong.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Mama-hong.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/04\/Mama-hong.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                            <\/div>\n                                                                        <\/div><!--end of grid-module__item-->\n                                                                <div class=\"grid-module__item\">\n                                    <div class=\"text-comp-wrap\">\n                                        <h4>Bubble Tea<\/h4>\n                                        <p>Wij bieden de tools om de service te stroomlijnen en piekuren moeiteloos te beheren. En dat alles terwijl je een loyale klantenkring opbouwt.<\/p>\n\n                                        <div class=\"btns-wrap\">\n                                                <div class=\"btn light-gray-btn\">\n        <a  href=\"https:\/\/eatcard.nl\/nl\/business-type\/bubble-tea\/\">Ontdek Bubble Tea<\/a>\n    <\/div>\n                                        <\/div><!--end of btns-wrap-->\n                                    <\/div><!--end of text-comp-wrap-->\n                                                                            <div class=\"logo-blocks-wrap\">\n                                                                                                <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-19.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-19.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-19.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-18.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-18.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-18.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-16.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-16.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-16.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-17.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-17.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Frame-17.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                                        <div class=\"logo-blocks-wrap__item\">\n                                                        \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/06\/Blue-Cup-1.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/06\/Blue-Cup-1.jpg'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2026\/06\/Blue-Cup-1.jpg\">    <\/picture>\n\n                                                    <\/div><!--end of logo-blocks-wrap__item-->\n                                                                                            <\/div>\n                                                                        <\/div><!--end of grid-module__item-->\n                                                            <div class=\"grid-module__item grid-module__item--two-third\">\n                                <div class=\"grid-module__item-left\">\n                                    <div class=\"text-comp-wrap\">\n                                        <h4>Ontdek hoe wij jouw type bedrijf kunnen helpen<\/h4>\n<p>Eatcard geeft je de tools om je bedrijfsvoering te stroomlijnen en de effici\u00ebntie te verhogen, terwijl je gasten een unieke ervaring beleven.<\/p>\n<ul>\n<li><a href=\"https:\/\/eatcard.nl\/nl\/business-type\/fine-dining\/\">Fine Dining<\/a><\/li>\n<li><a href=\"https:\/\/eatcard.nl\/nl\/business-type\/all-you-can-eat\/\">All you can eat<\/a><\/li>\n<li><a href=\"https:\/\/eatcard.nl\/nl\/business-type\/fast-dining\/\">Fast Dining<\/a><\/li>\n<li><a href=\"https:\/\/eatcard.nl\/nl\/business-type\/koffie-en-cafe\/\">Koffie en caf\u00e9<\/a><\/li>\n<li><a href=\"https:\/\/eatcard.nl\/nl\/business-type\/korean-bbq\/\">Korean BBQ<\/a><\/li>\n<li><a href=\"https:\/\/eatcard.nl\/nl\/business-type\/bubble-tea\/\">Bubble Tea<\/a><\/li>\n<li><a href=\"https:\/\/eatcard.nl\/nl\/business-type\/ijssalon\/\">Ijssalon<\/a><\/li>\n<li><a href=\"https:\/\/eatcard.nl\/nl\/business-types\/\">Ontdek alle business types<\/a><\/li>\n<\/ul>\n                                    <\/div><!--end of text-comp-wrap-->\n                                <\/div><!--end of grid-module__item-left-->\n\n                                <div class=\"grid-module__item-right\">\n                                    <div class=\"grid-module__full-img\">\n                                                                            <\/div><!--end of grid-module__full-img-->\n                                <\/div><!--end of grid-module__item-right-->\n                            <\/div><!--end of grid-module__item-->\n                                                <div class=\"grid-module__item grid-module__item--cta\">\n                                                    <div class=\"text-comp-wrap\">\n                                <h4>Laten we samen jouw restaurant laten groeien.<\/h4>\n<p>Ons team staat klaar om jouw behoeften te begrijpen en je te helpen de perfecte Eatcard oplossing te vinden.<\/p>\n\n                                                                    <div class=\"btns-wrap\">\n                                        <div class=\"btn default\">\n                                            <a href=\"https:\/\/eatcard.nl\/nl\/book-a-demo\/\">Plan een demo<\/a>\n                                        <\/div>\n                                    <\/div>\n                                                                <\/div><!--end of text-comp-wrap-->\n\n                            <div class=\"grid-module__bottom-img\">\n                                \n    \n    <picture>\n                    <source type='image\/webp' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Yanniek-1.webp'>                    <source type='image\/png' srcset='https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Yanniek-1.webp'>        <img decoding=\"async\" alt=\"\" src=\"https:\/\/eatcard.nl\/wp-content\/uploads\/2025\/07\/Yanniek-1.webp\">    <\/picture>\n\n                            <\/div><!--end of grid-module__bottom-img-->\n                                                <\/div><!--end of grid-module__item-->\n                                <\/div><!--end of grid-module-->\n        <\/div><!--end of inner-->\n    <\/div><!--end of services-block-module-->\n    ","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6045","solution","type-solution","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/eatcard.nl\/nl\/wp-json\/wp\/v2\/solution\/6045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eatcard.nl\/nl\/wp-json\/wp\/v2\/solution"}],"about":[{"href":"https:\/\/eatcard.nl\/nl\/wp-json\/wp\/v2\/types\/solution"}],"version-history":[{"count":3,"href":"https:\/\/eatcard.nl\/nl\/wp-json\/wp\/v2\/solution\/6045\/revisions"}],"predecessor-version":[{"id":19134,"href":"https:\/\/eatcard.nl\/nl\/wp-json\/wp\/v2\/solution\/6045\/revisions\/19134"}],"wp:attachment":[{"href":"https:\/\/eatcard.nl\/nl\/wp-json\/wp\/v2\/media?parent=6045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}